{"id":317809,"date":"2026-05-12T12:21:51","date_gmt":"2026-05-12T17:21:51","guid":{"rendered":"https:\/\/www.celsia.com\/es\/?post_type=noticias&#038;p=317809"},"modified":"2026-05-12T12:23:31","modified_gmt":"2026-05-12T17:23:31","slug":"nuevas-inversiones-de-celsia-en-el-sur-del-tolima-elevan-la-confiabilidad-del-servicio-de-energia-en-7-municipios","status":"publish","type":"noticias","link":"https:\/\/www.celsia.com\/en\/noticias\/nuevas-inversiones-de-celsia-en-el-sur-del-tolima-elevan-la-confiabilidad-del-servicio-de-energia-en-7-municipios\/","title":{"rendered":"Nuevas inversiones de Celsia en el sur del Tolima elevan la confiabilidad del servicio de energ\u00eda en 7 municipios"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutos<\/span><\/span>","protected":false},"featured_media":0,"template":"","categorias_noticias":[40,32],"class_list":["post-317809","noticias","type-noticias","status-publish","hentry","categorias_noticias-noticias","categorias_noticias-sala-de-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.celsia.com\/en\/wp-json\/wp\/v2\/noticias\/317809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celsia.com\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.celsia.com\/en\/wp-json\/wp\/v2\/types\/noticias"}],"wp:attachment":[{"href":"https:\/\/www.celsia.com\/en\/wp-json\/wp\/v2\/media?parent=317809"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/www.celsia.com\/en\/wp-json\/wp\/v2\/categorias_noticias?post=317809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}